{"id":460,"name":"Julia Parkhomets","url":"","description":"","link":"https:\/\/iedinburgh.info\/uk\/author\/juliaparkhomets","slug":"juliaparkhomets","avatar_urls":{"24":"https:\/\/iedinburgh.info\/wp-content\/uploads\/avatar-privacy\/cache\/user\/0\/e\/0e96559b9f5bd72cc4815378643d73fa7ff1beabdeb329b32533738e84c90557-24.jpg","48":"https:\/\/iedinburgh.info\/wp-content\/uploads\/avatar-privacy\/cache\/user\/0\/e\/0e96559b9f5bd72cc4815378643d73fa7ff1beabdeb329b32533738e84c90557-48.jpg","96":"https:\/\/iedinburgh.info\/wp-content\/uploads\/avatar-privacy\/cache\/user\/0\/e\/0e96559b9f5bd72cc4815378643d73fa7ff1beabdeb329b32533738e84c90557-96.jpg"},"meta":[],"_links":{"self":[{"href":"https:\/\/iedinburgh.info\/uk\/wp-json\/wp\/v2\/users\/460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iedinburgh.info\/uk\/wp-json\/wp\/v2\/users"}]}}